{"id":68,"date":"2026-02-12T20:15:29","date_gmt":"2026-02-12T20:15:29","guid":{"rendered":"https:\/\/projects.etc.cmu.edu\/it-takes-two-alices\/?page_id=68"},"modified":"2026-02-12T20:49:51","modified_gmt":"2026-02-12T20:49:51","slug":"team","status":"publish","type":"page","link":"https:\/\/projects.etc.cmu.edu\/it-takes-two-alices\/team\/","title":{"rendered":"The Team"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"team","meta":{"footnotes":""},"class_list":["post-68","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/projects.etc.cmu.edu\/it-takes-two-alices\/wp-json\/wp\/v2\/pages\/68","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/projects.etc.cmu.edu\/it-takes-two-alices\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/projects.etc.cmu.edu\/it-takes-two-alices\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/projects.etc.cmu.edu\/it-takes-two-alices\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/projects.etc.cmu.edu\/it-takes-two-alices\/wp-json\/wp\/v2\/comments?post=68"}],"version-history":[{"count":2,"href":"https:\/\/projects.etc.cmu.edu\/it-takes-two-alices\/wp-json\/wp\/v2\/pages\/68\/revisions"}],"predecessor-version":[{"id":96,"href":"https:\/\/projects.etc.cmu.edu\/it-takes-two-alices\/wp-json\/wp\/v2\/pages\/68\/revisions\/96"}],"wp:attachment":[{"href":"https:\/\/projects.etc.cmu.edu\/it-takes-two-alices\/wp-json\/wp\/v2\/media?parent=68"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}